{"id":27461,"date":"2020-05-26T12:53:00","date_gmt":"2020-05-26T10:53:00","guid":{"rendered":"https:\/\/www.consulmartravel.com\/sobre-nos\/"},"modified":"2026-06-03T19:12:40","modified_gmt":"2026-06-03T17:12:40","slug":"sobre-nos","status":"publish","type":"page","link":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/","title":{"rendered":"Sobre n\u00f3s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"27461\" class=\"elementor elementor-27461 elementor-3750\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94ae0a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"94ae0a5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c99796b sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"c99796b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d68ee0 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"7d68ee0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u2728Sobre n\u00f3s\u2728<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9d17534 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"9d17534\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ecd7fc sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4ecd7fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d132e6e sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d132e6e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9648a54 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"9648a54\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1a897c sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a1a897c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd14239 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"fd14239\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ag\u00eancia de viagens (DMC) na Guin\u00e9-Bissau: turismo respons\u00e1vel e transporte mar\u00edtimo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16050dc elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"16050dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66e0252 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"66e0252\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b036d42 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"b036d42\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286b557 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"286b557\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"304\" data-end=\"517\"><span style=\"color: #000000;\" data-olk-copy-source=\"MessageBody\">Somos uma ag\u00eancia de viagens recetiva (Destination Management Company) na Guin\u00e9-Bissau, combinando o transporte mar\u00edtimo com o turismo respons\u00e1vel para oferecer experi\u00eancias aut\u00eanticas e sustent\u00e1veis.<\/span><\/p><p><span style=\"color: #000000;\" data-olk-copy-source=\"MessageBody\">A nossa hist\u00f3ria come\u00e7ou em 2017, quando trouxemos para a Guin\u00e9-Bissau a nossa experi\u00eancia de 70 anos em Espanha dedicada aos servi\u00e7os mar\u00edtimos, estabelecendo no pa\u00eds um <span style=\"color: #339966; text-decoration: underline;\"><span style=\"color: #339966;\"><a style=\"color: #339966; text-decoration: underline;\" title=\"https:\/\/www.consulmartravel.com\/ferry-archipielago-bijagos\/\" href=\"https:\/\/www.consulmartravel.com\/pt-pt\/balsa\/\" data-auth=\"NotApplicable\" data-linkindex=\"0\">servi\u00e7o regular de ferry<\/a><\/span><\/span> entre a capital Bissau e as Ilhas Bijag\u00f3s. Com o tempo, esta atividade levou-nos a criar um servi\u00e7o de transporte para turistas em l<a style=\"color: #000000; text-decoration: underline;\" title=\"https:\/\/www.consulmartravel.com\/pt-pt\/lancha\/\" href=\"https:\/\/www.consulmartravel.com\/pt-pt\/lancha\/\" data-auth=\"NotApplicable\" data-linkindex=\"1\">anchas r\u00e1pidas,<\/a> tanto para os hot\u00e9is nas ilhas como em rotas personalizadas, conectando os viajantes com as comunidades locais e o ambiente natural. <\/span><\/p><p><span style=\"color: #000000;\"><span class=\"TextRun SCXW149838635 BCX8\" lang=\"ES-ES\" data-contrast=\"auto\">Hoje, continuamos a apostar num turismo respons\u00e1vel, organizando viagens seguras e \u00fanicas gra\u00e7as a uma equipa local com um profundo conhecimento do territ\u00f3rio.<span class=\"NormalTextRun SCXW149838635 BCX8\">. Com esta abordagem, trabalhamos tanto com ag\u00eancias como com clientes individuais, consolidando-nos como um operador de confian\u00e7a no destino, com um profundo conhecimento do territ\u00f3rio e uma opera\u00e7\u00e3o fi\u00e1vel e adaptada a cada projeto.<\/span><\/span><span class=\"EOP Selected SCXW149838635 BCX8\" data-ccp-props=\"{\"201341983\":0,\"335559740\":300}\"> <\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49d0b8b elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"49d0b8b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9537b37 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"9537b37\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-966a2bb sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"966a2bb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14219e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"14219e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5a147e sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f5a147e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4faf6ad sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4faf6ad\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b7509c elementor-widget__width-initial elementor-sticky elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"4b7509c\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;sticky&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.consulmartravel.com\/ferry\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Rota regular de ferry\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-anchor\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.consulmartravel.com\/ferry\/\" >\n\t\t\t\t\t\t\tRota regular de ferry\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOferecemos um transporte seguro de passageiros e mercadorias entre o continente e as ilhas.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-09a12e8 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"09a12e8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f99d06 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"7f99d06\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5224d3a elementor-widget__width-initial elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"5224d3a\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.consulmartravel.com\/pt-pt\/lancha\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Servi\u00e7o de lancha r\u00e1pida\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-vest\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.consulmartravel.com\/pt-pt\/lancha\/\" >\n\t\t\t\t\t\t\tServi\u00e7o de lancha r\u00e1pida\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEspecialmente concebido para turistas e excurs\u00f5es, permite-te explorar o arquip\u00e9lago de forma r\u00e1pida e confort\u00e1vel.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-677d04b elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"677d04b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c22bc23 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"c22bc23\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb8d39d sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"cb8d39d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b48aef2 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"b48aef2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg\" class=\"attachment-medium_large size-medium_large wp-image-27468\" alt=\"\" srcset=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg 768w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-300x225.jpg 300w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-1024x768.jpg 1024w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-1536x1152.jpg 1536w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-370x278.jpg 370w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-840x630.jpg 840w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-410x308.jpg 410w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-720x540.jpg 720w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1.jpg 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26c3be4 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"26c3be4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-024ab6e elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"024ab6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18ca1b2 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"18ca1b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce1351 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4ce1351\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cf494c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"cf494c0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdb200a sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"fdb200a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8398e76 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"8398e76\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83e\udde0A nossa filosofia\ud83e\udde0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a60531 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"6a60531\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bb0f69 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"0bb0f69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89099d9 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"89099d9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5cce457 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"5cce457\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-995d3bd sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"995d3bd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0bf2408 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0bf2408\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac93df1 elementor-widget__width-initial sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"ac93df1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">Vis\u00e3o<\/h3><p><span style=\"color: #000000;\"> Tornar-nos a principal refer\u00eancia de viagens na Guin\u00e9-Bissau, oferecendo aos viajantes a oportunidade de viver experi\u00eancias inesquec\u00edveis enquanto promovemos um turismo respons\u00e1vel que contribua para o bem-estar das comunidades locais e para a preserva\u00e7\u00e3o do seu extraordin\u00e1rio patrim\u00f3nio cultural e natural.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2865f94 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"2865f94\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4932e3a sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4932e3a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8eda0a elementor-widget__width-inherit sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"f8eda0a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 style=\"text-align: left;\">Miss\u00e3o\ud83e\udded<\/h3><p><span style=\"color: #000000;\">Criamos viagens \u00fanicas e personalizadas na Guin\u00e9-Bissau, apoiando-nos numa equipa local com um profundo conhecimento do pa\u00eds, para conectar os viajantes com a magia e a autenticidade das suas culturas e paisagens, promovendo um turismo consciente e exclusivo.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bb85fd elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1bb85fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-491b92f sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"491b92f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dc4fbc sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"1dc4fbc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a907042 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a907042\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a357b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"5a357b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f95b9dd sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f95b9dd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2950d3b sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"2950d3b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3> 1\ud83d\udc8e<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8920060 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"8920060\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af4d31f elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"af4d31f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-859b8a6 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"859b8a6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad1a677 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"ad1a677\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d340d65 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"d340d65\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-star\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<h4 data-pm-slice=\"1 1 [\"document\",{\"aiOptions\":{\"preserveLayouts\":false,\"imageOptions\":{\"license\":\"All\",\"provider\":\"aiGenerated\",\"generateStyle\":\"light green white cool, friendly playful elegant clean modern fresh\",\"model\":\"ideogram-v3-turbo\",\"stylePreset\":\"Theme\"<\/i>,\"docId\":\"ygag1pubfqjhaxv\",\"background\":{\"type\":\"none\"},\"docFlags\":{\"cardLayoutsEnabled\":true},\"format\":\"webpage\",\"customCode\":{},\"settings\":{\"defaultFullBleed\":\"full\",\"stylesDerivedFrom\":\"webpage_fluid\",\"cardDimensions\":\"fluid\",\"verticalAlign\":\"center\",\"defaultContentWidth\":\"lg\",\"fontSize\":\"sm\",\"scaleContentToFit\":false,\"animationsEnabled\":true},\"generateStatus\":\"done\",\"generateInfo\":{\"interactionId\":\"ue9dfz3lxjjw0xg\",\"streamId\":\"ygag1pubfqjhaxv\",\"lastEventId\":\"8\",\"lastCompletedCardId\":\"v2xeagebq9qzcma\",\"lastCompletedCardIndex\":7<\/i>,\"card\",{\"id\":\"qeub0pkr2fg4nxq\",\"previewContent\":null,\"background\":{\"type\":\"none\"},\"container\":{},\"cardSize\":\"default\",\"layout\":\"left\",\"layoutTemplateColumns\":null,\"layoutTemplateRows\":null,\"verticalAlign\":null,\"generatorInput\":null,\"fontScale\":null,\"cardMarginSettings\":{},\"hidden\":false},\"cardLayoutItem\",{\"itemId\":\"body\"},\"smartLayout\",{\"variantKey\":\"iconsText\",\"options\":{\"cellSize\":20,\"imagePosition\":\"left\"},\"fullWidthBlock\":false},\"smartLayoutCell\",{\"id\":\"LUSXv\",\"options\":{},\"width\":null,\"image\":{\"loadImageParams\":{\"provider\":\"fontawesome\",\"query\":\"authenticity\",\"options\":{\"license\":\"All\"<\/i>,\"source\":\"image.icon\",\"loadImageStatus\":\"done\",\"loadImageId\":\"7JhWz\",\"src\":\"https:\/\/gamma.app\/api\/icons\/comment.svg?provider=fa&style=light\",\"tempUrl\":\"\",\"meta\":{\"height\":512,\"width\":512},\"query\":\"authenticity\",\"uploadStatus\":3},\"label\":null}]\">Autenticidade<\/h4>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOferecemos experi\u00eancias genu\u00ednas que conectam com a ess\u00eancia cultural e natural do Arquip\u00e9lago dos Bijag\u00f3s.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-cebf795 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"cebf795\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c332487 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c332487\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63297a4 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"63297a4\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-compress-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<div data-id=\"evuWj\" id=\"evuWj\" data-options=\"{}\" data-image=\"{\"loadImageParams\":{\"provider\":\"fontawesome\",\"query\":\"sustainability\",\"options\":{\"license\":\"All\"<\/i>,\"source\":\"image.icon\",\"loadImageStatus\":\"done\",\"loadImageId\":\"ipoEO\",\"src\":\"https:\/\/gamma.app\/api\/icons\/magnifying-glass.svg?provider=fa&style=light\",\"tempUrl\":\"\",\"meta\":{\"height\":512,\"width\":512},\"query\":\"sustainability\",\"uploadStatus\":3}\" class=\"layout-item\" data-pm-slice=\"0 0 []\"><h4>Respeito<\/h4><p class=\"paragraph\">Promovemos um turismo sustent\u00e1vel que protege as comunidades locais e a biodiversidade do ambiente<\/p><\/div>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f2188bf sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f2188bf\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0f2d0f sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e0f2d0f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61b6643 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"61b6643\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-check-circle\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<div data-id=\"evuWj\" id=\"evuWj\" data-options=\"{}\" data-image=\"{\"loadImageParams\":{\"provider\":\"fontawesome\",\"query\":\"sustainability\",\"options\":{\"license\":\"All\"<\/i>,\"source\":\"image.icon\",\"loadImageStatus\":\"done\",\"loadImageId\":\"ipoEO\",\"src\":\"https:\/\/gamma.app\/api\/icons\/magnifying-glass.svg?provider=fa&style=light\",\"tempUrl\":\"\",\"meta\":{\"height\":512,\"width\":512},\"query\":\"sustainability\",\"uploadStatus\":3}\" class=\"layout-item\" data-pm-slice=\"0 0 []\"><h4>Excel\u00eancia<\/h4><\/div>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tCuidamos de todos os pormenores para garantir experi\u00eancias excepcionais a todos os nossos viajantes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-17c9c60 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"17c9c60\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62e2a7d sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"62e2a7d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c1d329 elementor-view-default elementor-position-top elementor-mobile-position-top sc_fly_static elementor-widget elementor-widget-icon-box\" data-id=\"8c1d329\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-down\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t<div data-id=\"evuWj\" id=\"evuWj\" data-options=\"{}\" data-image=\"{\"loadImageParams\":{\"provider\":\"fontawesome\",\"query\":\"sustainability\",\"options\":{\"license\":\"All\"<\/i>,\"source\":\"image.icon\",\"loadImageStatus\":\"done\",\"loadImageId\":\"ipoEO\",\"src\":\"https:\/\/gamma.app\/api\/icons\/magnifying-glass.svg?provider=fa&style=light\",\"tempUrl\":\"\",\"meta\":{\"height\":512,\"width\":512},\"query\":\"sustainability\",\"uploadStatus\":3}\" class=\"layout-item\" data-pm-slice=\"0 0 []\"><h4>Integridade<\/h4><\/div>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMantemos a honestidade e a clareza em todas as nossas intera\u00e7\u00f5es com clientes e parceiros.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ea0835 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"6ea0835\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7df350c sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"7df350c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6531d54 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6531d54\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc190d sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"7fc190d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udc65A nossa equipa\ud83d\udc65<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a650b0d elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"a650b0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a721117 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a721117\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0eb32a sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"f0eb32a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76294fd elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"76294fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a9b5b9 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"6a9b5b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-615a4a6 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"615a4a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"172\" data-end=\"204\"><span style=\"color: #000000;\">A nossa equipa combina a experi\u00eancia internacional de profissionais europeus com o conhecimento local de especialistas guineenses. Esta sinergia permite-nos oferecer um planeamento meticuloso e personalizado, adaptado a cada viajante<\/span><\/p><div class=\"column\" data-pm-slice=\"2 2 [\"document\",{\"aiOptions\":{\"preserveLayouts\":false,\"imageOptions\":{\"license\":\"All\",\"provider\":\"aiGenerated\",\"generateStyle\":\"light green white cool, friendly playful elegant clean modern fresh\",\"model\":\"ideogram-v3-turbo\",\"stylePreset\":\"Theme\"}},\"docId\":\"ygag1pubfqjhaxv\",\"background\":{\"type\":\"none\"},\"docFlags\":{\"cardLayoutsEnabled\":true},\"format\":\"webpage\",\"customCode\":{},\"settings\":{\"defaultFullBleed\":\"full\",\"stylesDerivedFrom\":\"webpage_fluid\",\"cardDimensions\":\"fluid\",\"verticalAlign\":\"center\",\"defaultContentWidth\":\"lg\",\"fontSize\":\"sm\",\"scaleContentToFit\":false,\"animationsEnabled\":true},\"generateStatus\":\"done\",\"generateInfo\":{\"interactionId\":\"ue9dfz3lxjjw0xg\",\"streamId\":\"ygag1pubfqjhaxv\",\"lastEventId\":\"8\",\"lastCompletedCardId\":\"v2xeagebq9qzcma\",\"lastCompletedCardIndex\":7}},\"card\",{\"id\":\"fg35bstcmrccpbz\",\"previewContent\":null,\"background\":{\"type\":\"none\"},\"container\":{},\"cardSize\":\"default\",\"layout\":\"blank\",\"layoutTemplateColumns\":null,\"layoutTemplateRows\":null,\"verticalAlign\":null,\"generatorInput\":null,\"fontScale\":null,\"cardMarginSettings\":{},\"hidden\":false},\"cardLayoutItem\",{\"itemId\":\"body\"},\"gridLayout\",{\"colWidths\":[50,50],\"fullWidthBlock\":false}]\"><p class=\"paragraph\"><span style=\"color: #000000;\">O dom\u00ednio de v\u00e1rios idiomas facilita que turistas de todo o mundo se sintam bem-vindos e compreendidos durante a sua estadia na Guin\u00e9-Bissau.<\/span><\/p><p data-start=\"657\" data-end=\"999\"><span style=\"color: #000000;\">Tudo isto com um compromisso firme com o turismo respons\u00e1vel: respeitando a cultura local, valorizando as comunidades e cuidando de cada detalhe para proporcionar uma experi\u00eancia consciente e transformadora.<\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07839e3 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"07839e3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70efd6a sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"70efd6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2542e2 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"f2542e2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"811\" src=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-1024x811.jpg\" class=\"attachment-large size-large wp-image-29558\" alt=\"Equipo\" srcset=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-1024x811.jpg 1024w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-300x238.jpg 300w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-768x608.jpg 768w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-1536x1216.jpg 1536w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-370x293.jpg 370w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-840x665.jpg 840w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal-410x325.jpg 410w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/10\/Personal.jpg 1798w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baf6a74 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"baf6a74\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e21fa1 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"0e21fa1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a4ed0df sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"a4ed0df\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e69bad3 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"e69bad3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2676255 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"2676255\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><span style=\"color: #000000;\">Os nossos guias\ud83e\udded<\/span><\/h3><p class=\"paragraph\" data-pm-slice=\"1 1 [\"document\",{\"aiOptions\":{\"preserveLayouts\":false,\"imageOptions\":{\"license\":\"All\",\"provider\":\"aiGenerated\",\"generateStyle\":\"light green white cool, friendly playful elegant clean modern fresh\",\"model\":\"ideogram-v3-turbo\",\"stylePreset\":\"Theme\"}},\"docId\":\"ygag1pubfqjhaxv\",\"background\":{\"type\":\"none\"},\"docFlags\":{\"cardLayoutsEnabled\":true},\"format\":\"webpage\",\"customCode\":{},\"settings\":{\"defaultFullBleed\":\"full\",\"stylesDerivedFrom\":\"webpage_fluid\",\"cardDimensions\":\"fluid\",\"verticalAlign\":\"center\",\"defaultContentWidth\":\"lg\",\"fontSize\":\"sm\",\"scaleContentToFit\":false,\"animationsEnabled\":true},\"generateStatus\":\"done\",\"generateInfo\":{\"interactionId\":\"ue9dfz3lxjjw0xg\",\"streamId\":\"ygag1pubfqjhaxv\",\"lastEventId\":\"8\",\"lastCompletedCardId\":\"v2xeagebq9qzcma\",\"lastCompletedCardIndex\":7}},\"card\",{\"id\":\"bl3idyb3sa0eusf\",\"previewContent\":null,\"background\":{\"type\":\"none\"},\"container\":{\"background\":{\"type\":\"color\",\"color\":{\"hex\":\"#000000\"}}},\"cardSize\":\"default\",\"layout\":\"behind\",\"layoutTemplateColumns\":null,\"layoutTemplateRows\":null,\"verticalAlign\":null,\"generatorInput\":null,\"fontScale\":null,\"cardMarginSettings\":{},\"hidden\":false},\"cardLayoutItem\",{\"itemId\":\"body\"},\"smartLayout\",{\"variantKey\":\"textBoxes\",\"options\":{\"cellSize\":20},\"fullWidthBlock\":false},\"smartLayoutCell\",{\"id\":\"caUEO\",\"options\":{},\"width\":null,\"image\":null,\"label\":null}]\"><span style=\"color: #000000;\">Os nossos guias s\u00e3o verdadeiros embaixadores culturais da Guin\u00e9-Bissau. Conhecem profundamente as etnias, tradi\u00e7\u00f5es, religi\u00f5es, fauna e flora do pa\u00eds. Com paix\u00e3o e dedica\u00e7\u00e3o, transformam cada excurs\u00e3o numa experi\u00eancia educativa e inspiradora.  <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1fecc7 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"f1fecc7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-edb85b9 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"edb85b9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4412a51 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"4412a51\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 data-start=\"850\" data-end=\"867\"><span style=\"color: #000000;\"><span style=\"color: #000000;\">Marinheiros experientes<\/span><\/span>\u2693<\/h3><div id=\"Ftbby\" class=\"layout-item\" data-id=\"Ftbby\" data-options=\"{}\" data-pm-slice=\"0 0 []\"><p class=\"paragraph\"><span style=\"color: #000000;\">Originarios del Archipi\u00e9lago Bijag\u00f3s, nuestros marineros conocen estas aguas como la palma de su mano. Su experiencia en corrientes, clima y rincones ocultos del archipi\u00e9lago garantiza una navegaci\u00f3n segura y de alta calidad. <\/span><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f08768 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"1f08768\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eb2ef15 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"eb2ef15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41a112e sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"41a112e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4d30fd3 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4d30fd3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc4de86 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"dc4de86\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e19c6a6 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e19c6a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cc58a2 elementor-widget-mobile__width-initial sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"6cc58a2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\ud83d\udea4A nossa frota\ud83d\udea4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce5e189 elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"ce5e189\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2307bea sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"2307bea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a70b0fe sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a70b0fe\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bc2aaa elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"3bc2aaa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e14d49a sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"e14d49a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-043e956 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"043e956\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-815eb6c sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"815eb6c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6cce2a sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"f6cce2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u2693 Dispomos de uma moderna frota de embarca\u00e7\u00f5es r\u00e1pidas<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-848272e sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"848272e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd864c4 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"fd864c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\ud83d\udd27Equipadas com motores at\u00e9 300 CV e capacidade para 18 pessoas.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9887786 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"9887786\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e878df6 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"e878df6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\ud83d\udee0\ufe0f Nuestros talleres se encargan del mantenimiento constante.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7550fdb sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"7550fdb\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c9012 sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"c1c9012\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u2705 Para garantir sempre o seu estado ideal e a m\u00e1xima seguran\u00e7a.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71ad45d sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"71ad45d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-84baf01 sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"84baf01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a192088 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"a192088\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e45b60a sc_fly_static elementor-widget elementor-widget-image\" data-id=\"e45b60a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"598\" src=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081.jpg\" class=\"attachment-large size-large wp-image-25426\" alt=\"\" srcset=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081.jpg 1024w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-300x175.jpg 300w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-768x449.jpg 768w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-370x216.jpg 370w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-840x491.jpg 840w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-410x239.jpg 410w, https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/03\/IMG-20220712-WA00081-720x420.jpg 720w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa151f sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"2aa151f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u2728Sobre n\u00f3s\u2728 Ag\u00eancia de viagens (DMC) na Guin\u00e9-Bissau: turismo respons\u00e1vel e transporte mar\u00edtimo Somos uma ag\u00eancia de viagens recetiva (Destination Management Company) na Guin\u00e9-Bissau, combinando o transporte mar\u00edtimo com o&hellip;<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-27461","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel<\/title>\n<meta name=\"description\" content=\"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel\" \/>\n<meta property=\"og:description\" content=\"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/\" \/>\n<meta property=\"og:site_name\" content=\"Consulmar Travel\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T17:12:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/\",\"url\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/\",\"name\":\"Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel\",\"isPartOf\":{\"@id\":\"https:\/\/www.consulmartravel.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg\",\"datePublished\":\"2020-05-26T10:53:00+00:00\",\"dateModified\":\"2026-06-03T17:12:40+00:00\",\"description\":\"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage\",\"url\":\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg\",\"contentUrl\":\"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.consulmartravel.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sobre n\u00f3s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.consulmartravel.com\/#website\",\"url\":\"https:\/\/www.consulmartravel.com\/\",\"name\":\"Consulmar Travel\",\"description\":\"Descubre la Magia de Guinea-Bissau y el Archipi\u00e9lago Bijag\u00f3s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.consulmartravel.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel","description":"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/","og_locale":"pt_PT","og_type":"article","og_title":"Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel","og_description":"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.","og_url":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/","og_site_name":"Consulmar Travel","article_modified_time":"2026-06-03T17:12:40+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/","url":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/","name":"Sobre n\u00f3s - Consulmar Travel transporte mar\u00edtimo e turismo respons\u00e1vel","isPartOf":{"@id":"https:\/\/www.consulmartravel.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage"},"image":{"@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg","datePublished":"2020-05-26T10:53:00+00:00","dateModified":"2026-06-03T17:12:40+00:00","description":"A Consulmar Travel oferece transporte mar\u00edtimo e turismo respons\u00e1vel desde 2017, conectando ilhas e criando experi\u00eancias \u00fanicas.","breadcrumb":{"@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#primaryimage","url":"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg","contentUrl":"https:\/\/www.consulmartravel.com\/wp-content\/uploads\/2025\/04\/8683f3ac-37e5-4c8f-9516-4b466cfe55e4-1-768x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.consulmartravel.com\/pt-pt\/sobre-nos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.consulmartravel.com\/"},{"@type":"ListItem","position":2,"name":"Sobre n\u00f3s"}]},{"@type":"WebSite","@id":"https:\/\/www.consulmartravel.com\/#website","url":"https:\/\/www.consulmartravel.com\/","name":"Consulmar Travel","description":"Descubre la Magia de Guinea-Bissau y el Archipi\u00e9lago Bijag\u00f3s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.consulmartravel.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/pages\/27461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=27461"}],"version-history":[{"count":12,"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/pages\/27461\/revisions"}],"predecessor-version":[{"id":29778,"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/pages\/27461\/revisions\/29778"}],"wp:attachment":[{"href":"https:\/\/www.consulmartravel.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=27461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}